{"id":957,"date":"2022-09-16T10:54:14","date_gmt":"2022-09-16T08:54:14","guid":{"rendered":"https:\/\/colossalstore.es\/?post_type=product&#038;p=957"},"modified":"2025-06-20T11:21:39","modified_gmt":"2025-06-20T09:21:39","slug":"tokyo-revengers-2","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/tokyo-revengers-2\/","title":{"rendered":"tokyo revengers 2"},"content":{"rendered":"<p>Tokyo Revengers 2 (Ken Wakui)<\/p>\n<p>Takemichi, a loser who was a member of a gang in his youth, jumps back in time 12 years to return to high school and save his ex-girlfriend, Hina, who has currently been murdered by the criminal organization Tokyo Manjikai. With each time travel, Takemichi influences those around him and little by little changes the past... but will that be enough to save Hina and prevent the Tokyo Manjikai from becoming a feared criminal gang?<\/p>","protected":false},"excerpt":{"rendered":"<p>Tokyo Revengers 2 (Ken Wakui) Takemichi, un fracasado que fue miembro de una banda en su juventud, salta 12 a\u00f1os atr\u00e1s en el tiempo para volver al instituto y salvar a su exnovia, Hina, que en la actualidad ha sido asesinada por la organizaci\u00f3n criminal Tokyo Manjikai. Con cada viaje temporal, Takemichi influye en los [&hellip;]<\/p>","protected":false},"featured_media":958,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[32],"product_tag":[],"class_list":{"0":"post-957","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-manga","8":"first","9":"outofstock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tokyo Revengers 2 (Ken Wakui) | Colossal Store<\/title>\n<meta name=\"description\" content=\"Tokyo Revengers 2 (Ken Wakui): Takemichi, un fracasado que fue miembro de una banda en su juventud, salta 12 a\u00f1os atr\u00e1s en el tiempo para volver al instituto y salvar a su exnovia, Hina, que en la actualidad ha sido asesinada por la organizaci\u00f3n criminal Tokyo Manjikai. Con cada viaje temporal, Takemichi influye en los que le rodean y poco a poco va cambiando el pasado\u2026 \u00bfpero eso ser\u00e1 suficiente para salvar a Hina y evitar que la Tokyo Manjikai se convierta en una temida banda criminal?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/tokyo-revengers-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tokyo Revengers 2 (Ken Wakui) | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Tokyo Revengers 2 (Ken Wakui): Takemichi, un fracasado que fue miembro de una banda en su juventud, salta 12 a\u00f1os atr\u00e1s en el tiempo para volver al instituto y salvar a su exnovia, Hina, que en la actualidad ha sido asesinada por la organizaci\u00f3n criminal Tokyo Manjikai. Con cada viaje temporal, Takemichi influye en los que le rodean y poco a poco va cambiando el pasado\u2026 \u00bfpero eso ser\u00e1 suficiente para salvar a Hina y evitar que la Tokyo Manjikai se convierta en una temida banda criminal?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/tokyo-revengers-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:21:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/thumb_19473_albumes_big.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"1187\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/\",\"name\":\"Tokyo Revengers 2 (Ken Wakui) | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/thumb_19473_albumes_big.jpeg\",\"datePublished\":\"2022-09-16T08:54:14+00:00\",\"dateModified\":\"2025-06-20T09:21:39+00:00\",\"description\":\"Tokyo Revengers 2 (Ken Wakui): Takemichi, un fracasado que fue miembro de una banda en su juventud, salta 12 a\u00f1os atr\u00e1s en el tiempo para volver al instituto y salvar a su exnovia, Hina, que en la actualidad ha sido asesinada por la organizaci\u00f3n criminal Tokyo Manjikai. Con cada viaje temporal, Takemichi influye en los que le rodean y poco a poco va cambiando el pasado\u2026 \u00bfpero eso ser\u00e1 suficiente para salvar a Hina y evitar que la Tokyo Manjikai se convierta en una temida banda criminal?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/thumb_19473_albumes_big.jpeg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/thumb_19473_albumes_big.jpeg\",\"width\":780,\"height\":1187},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tokyo Revengers 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tokyo Revengers 2 (Ken Wakui) | Colossal Store","description":"Tokyo Revengers 2 (Ken Wakui): Takemichi, un fracasado que fue miembro de una banda en su juventud, salta 12 a\u00f1os atr\u00e1s en el tiempo para volver al instituto y salvar a su exnovia, Hina, que en la actualidad ha sido asesinada por la organizaci\u00f3n criminal Tokyo Manjikai. Con cada viaje temporal, Takemichi influye en los que le rodean y poco a poco va cambiando el pasado\u2026 \u00bfpero eso ser\u00e1 suficiente para salvar a Hina y evitar que la Tokyo Manjikai se convierta en una temida banda criminal?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/tokyo-revengers-2\/","og_locale":"en_US","og_type":"article","og_title":"Tokyo Revengers 2 (Ken Wakui) | Colossal Store","og_description":"Tokyo Revengers 2 (Ken Wakui): Takemichi, un fracasado que fue miembro de una banda en su juventud, salta 12 a\u00f1os atr\u00e1s en el tiempo para volver al instituto y salvar a su exnovia, Hina, que en la actualidad ha sido asesinada por la organizaci\u00f3n criminal Tokyo Manjikai. Con cada viaje temporal, Takemichi influye en los que le rodean y poco a poco va cambiando el pasado\u2026 \u00bfpero eso ser\u00e1 suficiente para salvar a Hina y evitar que la Tokyo Manjikai se convierta en una temida banda criminal?","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/tokyo-revengers-2\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:21:39+00:00","og_image":[{"width":780,"height":1187,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/thumb_19473_albumes_big.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/","url":"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/","name":"Tokyo Revengers 2 (Ken Wakui) | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/thumb_19473_albumes_big.jpeg","datePublished":"2022-09-16T08:54:14+00:00","dateModified":"2025-06-20T09:21:39+00:00","description":"Tokyo Revengers 2 (Ken Wakui): Takemichi, un fracasado que fue miembro de una banda en su juventud, salta 12 a\u00f1os atr\u00e1s en el tiempo para volver al instituto y salvar a su exnovia, Hina, que en la actualidad ha sido asesinada por la organizaci\u00f3n criminal Tokyo Manjikai. Con cada viaje temporal, Takemichi influye en los que le rodean y poco a poco va cambiando el pasado\u2026 \u00bfpero eso ser\u00e1 suficiente para salvar a Hina y evitar que la Tokyo Manjikai se convierta en una temida banda criminal?","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/thumb_19473_albumes_big.jpeg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/thumb_19473_albumes_big.jpeg","width":780,"height":1187},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/tokyo-revengers-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Tokyo Revengers 2"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/958"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=957"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=957"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=957"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}