{"id":9560,"date":"2025-03-12T19:06:21","date_gmt":"2025-03-12T18:06:21","guid":{"rendered":"https:\/\/www.colossalstore.es\/?post_type=product&#038;p=9560"},"modified":"2025-06-20T11:14:04","modified_gmt":"2025-06-20T09:14:04","slug":"structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/","title":{"rendered":"Structure Deck Display Blue-Eyes white Destiny English \u2013 Yu-Gi-Oh!"},"content":{"rendered":"<p>Structure Deck Display Blue-Eyes white Destiny English \u2013 Yu-Gi-Oh!<\/p>","protected":false},"excerpt":{"rendered":"<p>Structure Deck Display Blue-Eyes white Destiny English \u2013 Yu-Gi-Oh!<\/p>","protected":false},"featured_media":9561,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[34,47],"product_tag":[],"class_list":{"0":"post-9560","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tcg","7":"product_cat-yu-gi-oh","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Structure Deck Display Blue-Eyes white Destiny Ingl\u00e9s - Yu-Gi-Oh! | Colossal Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Structure Deck Display Blue-Eyes white Destiny Ingl\u00e9s - Yu-Gi-Oh! | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Structure Deck Display Blue-Eyes white Destiny Ingl\u00e9s &#8211; Yu-Gi-Oh!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:14:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/03\/structure-deck-display-8-decks-blue-eyes-white-destiny-ingles-yu-gi-oh.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/\",\"name\":\"Structure Deck Display Blue-Eyes white Destiny Ingl\u00e9s - Yu-Gi-Oh! | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/03\/structure-deck-display-8-decks-blue-eyes-white-destiny-ingles-yu-gi-oh.webp\",\"datePublished\":\"2025-03-12T18:06:21+00:00\",\"dateModified\":\"2025-06-20T09:14:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/03\/structure-deck-display-8-decks-blue-eyes-white-destiny-ingles-yu-gi-oh.webp\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/03\/structure-deck-display-8-decks-blue-eyes-white-destiny-ingles-yu-gi-oh.webp\",\"width\":600,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Structure Deck Display Blue-Eyes white Destiny Ingl\u00e9s &#8211; Yu-Gi-Oh!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Structure Deck Display Blue-Eyes white Destiny Ingl\u00e9s - Yu-Gi-Oh! | Colossal Store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/","og_locale":"en_US","og_type":"article","og_title":"Structure Deck Display Blue-Eyes white Destiny Ingl\u00e9s - Yu-Gi-Oh! | Colossal Store","og_description":"Structure Deck Display Blue-Eyes white Destiny Ingl\u00e9s &#8211; Yu-Gi-Oh!","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:14:04+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/03\/structure-deck-display-8-decks-blue-eyes-white-destiny-ingles-yu-gi-oh.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/","url":"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/","name":"Structure Deck Display Blue-Eyes white Destiny Ingl\u00e9s - Yu-Gi-Oh! | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/03\/structure-deck-display-8-decks-blue-eyes-white-destiny-ingles-yu-gi-oh.webp","datePublished":"2025-03-12T18:06:21+00:00","dateModified":"2025-06-20T09:14:04+00:00","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/03\/structure-deck-display-8-decks-blue-eyes-white-destiny-ingles-yu-gi-oh.webp","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/03\/structure-deck-display-8-decks-blue-eyes-white-destiny-ingles-yu-gi-oh.webp","width":600,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/yu-gi-oh\/structure-deck-display-blue-eyes-white-destiny-ingles-yu-gi-oh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Structure Deck Display Blue-Eyes white Destiny Ingl\u00e9s &#8211; Yu-Gi-Oh!"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/9560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=9560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/9561"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=9560"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=9560"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=9560"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=9560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}