{"id":9159,"date":"2024-11-20T13:14:22","date_gmt":"2024-11-20T12:14:22","guid":{"rendered":"https:\/\/www.colossalstore.es\/?post_type=product&#038;p=9159"},"modified":"2025-06-23T13:57:39","modified_gmt":"2025-06-23T11:57:39","slug":"just-sleeves-japanese-size-green-60-sleeves","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/","title":{"rendered":"JUST SLEEVES &#8211; JAPANESE SIZE GREEN (60 SLEEVES)"},"content":{"rendered":"<p>Just Sleeves \u2013 Japanese Size Green (60 Sleeves)<\/p>\n<p>Easy to shuffle, acid free, PVC free. Compatible with: Yu-Gi-Oh! ?Naruto?, ?and many, many more!<\/p>","protected":false},"excerpt":{"rendered":"<p>Just Sleeves &#8211; Japanese Size Green (60 Sleeves) F\u00e1ciles de barajar, sin \u00e1cidos, sin PVC. Compatibles con: Yu-Gi-Oh! ?Naruto?, ?\u00a1y muchos, muchos m\u00e1s!<\/p>","protected":false},"featured_media":9160,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[35],"product_tag":[],"class_list":{"0":"post-9159","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accesorios","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Just Sleeves - Japanese Size Black (60 Sleeves) | Colossal Store<\/title>\n<meta name=\"description\" content=\"Just Sleeves - Japanese Size Black (60 Sleeves): F\u00e1ciles de barajar, sin \u00e1cidos, sin PVC. Compatibles con: Yu-Gi-Oh! ?Naruto?, ?\u00a1y muchos, muchos m\u00e1s!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Just Sleeves - Japanese Size Black (60 Sleeves) | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Just Sleeves - Japanese Size Black (60 Sleeves): F\u00e1ciles de barajar, sin \u00e1cidos, sin PVC. Compatibles con: Yu-Gi-Oh! ?Naruto?, ?\u00a1y muchos, muchos m\u00e1s!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-23T11:57:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/11\/comprar-japanese-size-green-60-just-sleeves-60-x-87-mm-gx1014-barato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"458\" \/>\n\t<meta property=\"og:image:height\" content=\"458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/\",\"name\":\"Just Sleeves - Japanese Size Black (60 Sleeves) | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/11\/comprar-japanese-size-green-60-just-sleeves-60-x-87-mm-gx1014-barato.jpg\",\"datePublished\":\"2024-11-20T12:14:22+00:00\",\"dateModified\":\"2025-06-23T11:57:39+00:00\",\"description\":\"Just Sleeves - Japanese Size Black (60 Sleeves): F\u00e1ciles de barajar, sin \u00e1cidos, sin PVC. Compatibles con: Yu-Gi-Oh! ?Naruto?, ?\u00a1y muchos, muchos m\u00e1s!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/11\/comprar-japanese-size-green-60-just-sleeves-60-x-87-mm-gx1014-barato.jpg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/11\/comprar-japanese-size-green-60-just-sleeves-60-x-87-mm-gx1014-barato.jpg\",\"width\":458,\"height\":458},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JUST SLEEVES &#8211; JAPANESE SIZE GREEN (60 SLEEVES)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Just Sleeves - Japanese Size Black (60 Sleeves) | Colossal Store","description":"Just Sleeves - Japanese Size Black (60 Sleeves): F\u00e1ciles de barajar, sin \u00e1cidos, sin PVC. Compatibles con: Yu-Gi-Oh! ?Naruto?, ?\u00a1y muchos, muchos m\u00e1s!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/","og_locale":"en_US","og_type":"article","og_title":"Just Sleeves - Japanese Size Black (60 Sleeves) | Colossal Store","og_description":"Just Sleeves - Japanese Size Black (60 Sleeves): F\u00e1ciles de barajar, sin \u00e1cidos, sin PVC. Compatibles con: Yu-Gi-Oh! ?Naruto?, ?\u00a1y muchos, muchos m\u00e1s!","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-23T11:57:39+00:00","og_image":[{"width":458,"height":458,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/11\/comprar-japanese-size-green-60-just-sleeves-60-x-87-mm-gx1014-barato.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/","url":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/","name":"Just Sleeves - Japanese Size Black (60 Sleeves) | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/11\/comprar-japanese-size-green-60-just-sleeves-60-x-87-mm-gx1014-barato.jpg","datePublished":"2024-11-20T12:14:22+00:00","dateModified":"2025-06-23T11:57:39+00:00","description":"Just Sleeves - Japanese Size Black (60 Sleeves): F\u00e1ciles de barajar, sin \u00e1cidos, sin PVC. Compatibles con: Yu-Gi-Oh! ?Naruto?, ?\u00a1y muchos, muchos m\u00e1s!","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/11\/comprar-japanese-size-green-60-just-sleeves-60-x-87-mm-gx1014-barato.jpg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/11\/comprar-japanese-size-green-60-just-sleeves-60-x-87-mm-gx1014-barato.jpg","width":458,"height":458},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/just-sleeves-japanese-size-green-60-sleeves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"JUST SLEEVES &#8211; JAPANESE SIZE GREEN (60 SLEEVES)"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/9159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=9159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/9160"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=9159"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=9159"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=9159"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=9159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}