{"id":8344,"date":"2024-07-10T19:34:18","date_gmt":"2024-07-10T17:34:18","guid":{"rendered":"https:\/\/www.colossalstore.es\/?post_type=product&#038;p=8344"},"modified":"2026-01-05T19:30:57","modified_gmt":"2026-01-05T18:30:57","slug":"frieren-9-kanehito-yamada-y-tsukasa-abe","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/","title":{"rendered":"FRIEREN 09"},"content":{"rendered":"<p>Frieren 9 \u2013 Kanehito Yamada and Tsukasa Abe<\/p>\n<div id=\"content\">\n<p>FRIEREN CONTINUES IN SEARCH OF THE LAND WHERE SOULS REST<\/p>\n<p>Motivated by the death of the hero Himmel, and in order to get to know people better, the magician Frieren embarks on a journey to Aureole, the land where souls rest, and where the Demon King&#039;s castle is located. As she advances across the northern plateau, fate leads her to meet Macht of the Golden Land, one of the seven sages of destruction. This story projects the memories that remain alive in the heart of the city of gold, bringing back the old times of those who were once heroes.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Frieren 9 &#8211; Kanehito Yamada y Tsukasa Abe FRIEREN SIGUE EN BUSCA DE LA TIERRA DONDE DESCANSAN LAS ALMAS Motivada por la muerte del h\u00e9roe Himmel, y con el fin de llegar a conocer mejor a las personas, la maga Frieren emprende un viaje hacia Aureole, la tierra en la que descansan las almas, y [&hellip;]<\/p>","protected":false},"featured_media":8345,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[32],"product_tag":[],"class_list":{"0":"post-8344","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-manga","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Frieren 9 - Kanehito Yamada y Tsukasa Abe | Colossal Store<\/title>\n<meta name=\"description\" content=\"Frieren 9 - Kanehito Yamada y Tsukasa Abe: Motivada por la muerte del h\u00e9roe Himmel, y con el fin de llegar a conocer mejor a las personas...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frieren 9 - Kanehito Yamada y Tsukasa Abe | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Frieren 9 - Kanehito Yamada y Tsukasa Abe: Motivada por la muerte del h\u00e9roe Himmel, y con el fin de llegar a conocer mejor a las personas...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-05T18:30:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/07\/Frieren-9.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"649\" \/>\n\t<meta property=\"og:image:height\" content=\"989\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/\",\"name\":\"Frieren 9 - Kanehito Yamada y Tsukasa Abe | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/07\/Frieren-9.jpeg\",\"datePublished\":\"2024-07-10T17:34:18+00:00\",\"dateModified\":\"2026-01-05T18:30:57+00:00\",\"description\":\"Frieren 9 - Kanehito Yamada y Tsukasa Abe: Motivada por la muerte del h\u00e9roe Himmel, y con el fin de llegar a conocer mejor a las personas...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/07\/Frieren-9.jpeg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/07\/Frieren-9.jpeg\",\"width\":649,\"height\":989},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FRIEREN 09\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frieren 9 - Kanehito Yamada y Tsukasa Abe | Colossal Store","description":"Frieren 9 - Kanehito Yamada y Tsukasa Abe: Motivada por la muerte del h\u00e9roe Himmel, y con el fin de llegar a conocer mejor a las personas...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/","og_locale":"en_US","og_type":"article","og_title":"Frieren 9 - Kanehito Yamada y Tsukasa Abe | Colossal Store","og_description":"Frieren 9 - Kanehito Yamada y Tsukasa Abe: Motivada por la muerte del h\u00e9roe Himmel, y con el fin de llegar a conocer mejor a las personas...","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/","og_site_name":"Colossal Store","article_modified_time":"2026-01-05T18:30:57+00:00","og_image":[{"width":649,"height":989,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/07\/Frieren-9.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/","url":"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/","name":"Frieren 9 - Kanehito Yamada y Tsukasa Abe | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/07\/Frieren-9.jpeg","datePublished":"2024-07-10T17:34:18+00:00","dateModified":"2026-01-05T18:30:57+00:00","description":"Frieren 9 - Kanehito Yamada y Tsukasa Abe: Motivada por la muerte del h\u00e9roe Himmel, y con el fin de llegar a conocer mejor a las personas...","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/07\/Frieren-9.jpeg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/07\/Frieren-9.jpeg","width":649,"height":989},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/frieren-9-kanehito-yamada-y-tsukasa-abe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"FRIEREN 09"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/8344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=8344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/8345"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=8344"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=8344"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=8344"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=8344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}