{"id":7740,"date":"2024-05-02T21:09:52","date_gmt":"2024-05-02T19:09:52","guid":{"rendered":"https:\/\/www.colossalstore.es\/?post_type=product&#038;p=7740"},"modified":"2025-06-20T11:15:31","modified_gmt":"2025-06-20T09:15:31","slug":"gamegenic-casual-album-24-pocket-black","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/","title":{"rendered":"Gamegenic \u2013 Casual Album 24- Pocket Black"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":7741,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[35],"product_tag":[],"class_list":{"0":"post-7740","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accesorios","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gamegenic - Casual Album 24- Pocket Black | Colossal Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gamegenic - Casual Album 24- Pocket Black | Colossal Store\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:15:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/05\/poridentidad.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/\",\"name\":\"Gamegenic - Casual Album 24- Pocket Black | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/05\/poridentidad.jpeg\",\"datePublished\":\"2024-05-02T19:09:52+00:00\",\"dateModified\":\"2025-06-20T09:15:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/05\/poridentidad.jpeg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/05\/poridentidad.jpeg\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gamegenic &#8211; Casual Album 24- Pocket Black\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gamegenic - Casual Album 24- Pocket Black | Colossal Store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/","og_locale":"en_US","og_type":"article","og_title":"Gamegenic - Casual Album 24- Pocket Black | Colossal Store","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:15:31+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/05\/poridentidad.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/","url":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/","name":"Gamegenic - Casual Album 24- Pocket Black | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/05\/poridentidad.jpeg","datePublished":"2024-05-02T19:09:52+00:00","dateModified":"2025-06-20T09:15:31+00:00","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/05\/poridentidad.jpeg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2024\/05\/poridentidad.jpeg","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-casual-album-24-pocket-black\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Gamegenic &#8211; Casual Album 24- Pocket Black"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/7740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=7740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/7741"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=7740"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=7740"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=7740"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=7740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}