{"id":749,"date":"2022-09-16T07:30:26","date_gmt":"2022-09-16T05:30:26","guid":{"rendered":"https:\/\/colossalstore.es\/?post_type=product&#038;p=749"},"modified":"2025-06-20T11:21:43","modified_gmt":"2025-06-20T09:21:43","slug":"cojin-monkey-d-luffy-one-piece","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/","title":{"rendered":"Monkey D. Luffy One Piece cushion"},"content":{"rendered":"<p>Luffy One Piece Cushion<\/p>\n<p>Franchise: One Piece<\/p>","protected":false},"excerpt":{"rendered":"<p>Cojin Luffy One Piece Franquicia: One Piece<\/p>","protected":false},"featured_media":750,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[22],"product_tag":[],"class_list":{"0":"post-749","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-peluches","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cojin Luffy One Piec | Colossal Store<\/title>\n<meta name=\"description\" content=\"Cojin Luffy One Piece: Franquicia: One Piece\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cojin Luffy One Piec | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Cojin Luffy One Piece: Franquicia: One Piece\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:21:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/img_242850_964adfd73ad75163ad9767cbc165060f_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"723\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/\",\"name\":\"Cojin Luffy One Piec | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/img_242850_964adfd73ad75163ad9767cbc165060f_1.jpg\",\"datePublished\":\"2022-09-16T05:30:26+00:00\",\"dateModified\":\"2025-06-20T09:21:43+00:00\",\"description\":\"Cojin Luffy One Piece: Franquicia: One Piece\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/img_242850_964adfd73ad75163ad9767cbc165060f_1.jpg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/img_242850_964adfd73ad75163ad9767cbc165060f_1.jpg\",\"width\":799,\"height\":723},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cojin Monkey D. Luffy One Piece\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cojin Luffy One Piec | Colossal Store","description":"Cojin Luffy One Piece: Franquicia: One Piece","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/","og_locale":"en_US","og_type":"article","og_title":"Cojin Luffy One Piec | Colossal Store","og_description":"Cojin Luffy One Piece: Franquicia: One Piece","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:21:43+00:00","og_image":[{"width":799,"height":723,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/img_242850_964adfd73ad75163ad9767cbc165060f_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/","url":"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/","name":"Cojin Luffy One Piec | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/img_242850_964adfd73ad75163ad9767cbc165060f_1.jpg","datePublished":"2022-09-16T05:30:26+00:00","dateModified":"2025-06-20T09:21:43+00:00","description":"Cojin Luffy One Piece: Franquicia: One Piece","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/img_242850_964adfd73ad75163ad9767cbc165060f_1.jpg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/img_242850_964adfd73ad75163ad9767cbc165060f_1.jpg","width":799,"height":723},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/peluches\/cojin-monkey-d-luffy-one-piece\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Cojin Monkey D. Luffy One Piece"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/750"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=749"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=749"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=749"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}