{"id":710,"date":"2022-09-16T02:54:27","date_gmt":"2022-09-16T00:54:27","guid":{"rendered":"https:\/\/colossalstore.es\/?post_type=product&#038;p=710"},"modified":"2025-06-20T11:21:43","modified_gmt":"2025-06-20T09:21:43","slug":"funko-pop-372-todoroki-my-hero-academia-serie-de-tv","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/","title":{"rendered":"Funko POP! 372 Todoroki \u2013 My Hero Academia \u2013 TV Series"},"content":{"rendered":"<p>Funko Todoroki Shoto (My Hero Academia) (#372)<\/p>\n<p>DATA SHEET:<\/p>\n<p>License: My Hero Academia<\/p>\n<p>Funko line: My Hero Academia<\/p>\n<p>Number: 372<\/p>","protected":false},"excerpt":{"rendered":"<p>Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ) FICHA T\u00c9CNICA: Licencia: My Hero Academia L\u00ednea de funkos: My Hero Academia N\u00famero: 372<\/p>","protected":false},"featured_media":711,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[20],"product_tag":[],"class_list":{"0":"post-710","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-funkos","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ) | Colossal Store<\/title>\n<meta name=\"description\" content=\"Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ): Licencia: My Hero Academia. L\u00ednea de funkos: My Hero Academia. N\u00famero: 372\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ) | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ): Licencia: My Hero Academia. L\u00ednea de funkos: My Hero Academia. N\u00famero: 372\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:21:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"367\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/\",\"name\":\"Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ) | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv.jpg\",\"datePublished\":\"2022-09-16T00:54:27+00:00\",\"dateModified\":\"2025-06-20T09:21:43+00:00\",\"description\":\"Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ): Licencia: My Hero Academia. L\u00ednea de funkos: My Hero Academia. N\u00famero: 372\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv.jpg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv.jpg\",\"width\":367,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Funko POP! 372 Todoroki &#8211; My Hero Academia &#8211; Serie De TV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ) | Colossal Store","description":"Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ): Licencia: My Hero Academia. L\u00ednea de funkos: My Hero Academia. N\u00famero: 372","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/","og_locale":"en_US","og_type":"article","og_title":"Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ) | Colossal Store","og_description":"Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ): Licencia: My Hero Academia. L\u00ednea de funkos: My Hero Academia. N\u00famero: 372","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:21:43+00:00","og_image":[{"width":367,"height":420,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/","url":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/","name":"Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ) | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv.jpg","datePublished":"2022-09-16T00:54:27+00:00","dateModified":"2025-06-20T09:21:43+00:00","description":"Funko Todoroki\u00a0 Shoto (My Hero Academia) (#372 ): Licencia: My Hero Academia. L\u00ednea de funkos: My Hero Academia. N\u00famero: 372","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv.jpg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv.jpg","width":367,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-372-todoroki-my-hero-academia-serie-de-tv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Funko POP! 372 Todoroki &#8211; My Hero Academia &#8211; Serie De TV"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/711"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=710"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=710"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=710"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}