{"id":6518,"date":"2023-11-17T19:02:45","date_gmt":"2023-11-17T18:02:45","guid":{"rendered":"https:\/\/www.colossalstore.es\/?post_type=product&#038;p=6518"},"modified":"2025-06-20T11:15:38","modified_gmt":"2025-06-20T09:15:38","slug":"one-piece-card-game-op06-booster-display-24-packs-en","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/","title":{"rendered":"One Piece Card Game OP06 Booster Display (24 Packs) \u2013 EN"},"content":{"rendered":"<p>One Piece Card Game OP06 Booster Display (24 Packs) \u2013 EN<\/p>\n<p>This pack focuses on fan favorites Zoro and Sanji.<br \/>\nIt offers great synergy with ST 12, as well as several popular characters that do not appear in ST 12.<\/p>\n<p>Introducing Sanji&#039;s sister, Reiju from Germa 66, along with MOVIE themed cards in new colors. Also includes Moria, Perona and other popular characters from throughout the series.<\/p>\n<p>The SP cards in this pack feature designs that capture a snapshot of the daily lives of various characters. This is a rare theme for merchandising products and is sure to appeal to collectors.<\/p>\n<p>Oddities:<\/p>\n<p>Leader x6<br \/>\nCommon x45<br \/>\nUncommon x30<br \/>\nRare x26<br \/>\nSuper Rare x10<br \/>\nRare Secret x2<br \/>\nSpecial card x6<br \/>\nDON! Letter x1<br \/>\n126 types of cards<\/p>","protected":false},"excerpt":{"rendered":"<p>One Piece Card Game OP06 Booster Display (24 Packs) &#8211; EN Este pack se centra en los favoritos de los fans, Zoro y Sanji. Ofrece una gran sinergia con ST 12, as\u00ed como varios personajes populares que no aparecen en ST 12. Presentamos a la hermana de Sanji, Reiju de Germa 66, junto con cartas [&hellip;]<\/p>","protected":false},"featured_media":6624,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[48,34],"product_tag":[],"class_list":{"0":"post-6518","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-one-piece","7":"product_cat-tcg","9":"first","10":"outofstock","11":"sale","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>One Piece Card Game OP06 Booster Display (24 Packs) - EN | Colossal Store<\/title>\n<meta name=\"description\" content=\"One Piece Card Game OP06 Booster Display (24 Packs) - EN: Este pack se centra en los favoritos de los fans, Zoro y Sanji. Ofrece una gran sinergia con ST 12, as\u00ed como varios personajes populares que no aparecen en ST 12.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"One Piece Card Game OP06 Booster Display (24 Packs) - EN | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"One Piece Card Game OP06 Booster Display (24 Packs) - EN: Este pack se centra en los favoritos de los fans, Zoro y Sanji. Ofrece una gran sinergia con ST 12, as\u00ed como varios personajes populares que no aparecen en ST 12.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:15:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/11\/3960132986.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/\",\"name\":\"One Piece Card Game OP06 Booster Display (24 Packs) - EN | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/11\/3960132986.jpg\",\"datePublished\":\"2023-11-17T18:02:45+00:00\",\"dateModified\":\"2025-06-20T09:15:38+00:00\",\"description\":\"One Piece Card Game OP06 Booster Display (24 Packs) - EN: Este pack se centra en los favoritos de los fans, Zoro y Sanji. Ofrece una gran sinergia con ST 12, as\u00ed como varios personajes populares que no aparecen en ST 12.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/11\/3960132986.jpg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/11\/3960132986.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"One Piece Card Game OP06 Booster Display (24 Packs) &#8211; EN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"One Piece Card Game OP06 Booster Display (24 Packs) - EN | Colossal Store","description":"One Piece Card Game OP06 Booster Display (24 Packs) - EN: Este pack se centra en los favoritos de los fans, Zoro y Sanji. Ofrece una gran sinergia con ST 12, as\u00ed como varios personajes populares que no aparecen en ST 12.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/","og_locale":"en_US","og_type":"article","og_title":"One Piece Card Game OP06 Booster Display (24 Packs) - EN | Colossal Store","og_description":"One Piece Card Game OP06 Booster Display (24 Packs) - EN: Este pack se centra en los favoritos de los fans, Zoro y Sanji. Ofrece una gran sinergia con ST 12, as\u00ed como varios personajes populares que no aparecen en ST 12.","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:15:38+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/11\/3960132986.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/","url":"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/","name":"One Piece Card Game OP06 Booster Display (24 Packs) - EN | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/11\/3960132986.jpg","datePublished":"2023-11-17T18:02:45+00:00","dateModified":"2025-06-20T09:15:38+00:00","description":"One Piece Card Game OP06 Booster Display (24 Packs) - EN: Este pack se centra en los favoritos de los fans, Zoro y Sanji. Ofrece una gran sinergia con ST 12, as\u00ed como varios personajes populares que no aparecen en ST 12.","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/11\/3960132986.jpg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/11\/3960132986.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/one-piece\/one-piece-card-game-op06-booster-display-24-packs-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"One Piece Card Game OP06 Booster Display (24 Packs) &#8211; EN"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/6518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=6518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/6624"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=6518"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=6518"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=6518"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=6518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}