{"id":557,"date":"2022-09-16T02:04:05","date_gmt":"2022-09-16T00:04:05","guid":{"rendered":"https:\/\/colossalstore.es\/?post_type=product&#038;p=557"},"modified":"2026-01-05T20:48:24","modified_gmt":"2026-01-05T19:48:24","slug":"funko-pop-squirtle-10-25-cm-pokemon","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/","title":{"rendered":"FUNKO POP! 10&#8243; POKEMON &#8211; LAPRAS 10&#8243; 25CM (EMEA)"},"content":{"rendered":"<p>Funko Squirtle 25cm (Pok\u00e9mon) (#505)<\/p>\n<p>DATA SHEET:<\/p>\n<p>License: pokemon<\/p>\n<p>Funko Line: Pokemon<\/p>\n<p>Number: 505<\/p>","protected":false},"excerpt":{"rendered":"<p>Funko Squirtle 25cm (Pok\u00e9mon) (#505) FICHA T\u00c9CNICA: Licencia: Pok\u00e9mon L\u00ednea de funkos: Pok\u00e9mon N\u00famero: 505<\/p>","protected":false},"featured_media":558,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[20],"product_tag":[],"class_list":{"0":"post-557","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-funkos","8":"first","9":"outofstock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Funko Squirtle 25cm (Pok\u00e9mon) (#505) | Colossal Store<\/title>\n<meta name=\"description\" content=\"Funko Squirtle 25cm (Pok\u00e9mon) (#505): Licencia: Pok\u00e9mon. L\u00ednea de funkos: Pok\u00e9mon. N\u00famero: 505\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funko Squirtle 25cm (Pok\u00e9mon) (#505) | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Funko Squirtle 25cm (Pok\u00e9mon) (#505): Licencia: Pok\u00e9mon. L\u00ednea de funkos: Pok\u00e9mon. N\u00famero: 505\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-05T19:48:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-squirtle-10-25-cm-pokemon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/\",\"name\":\"Funko Squirtle 25cm (Pok\u00e9mon) (#505) | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-squirtle-10-25-cm-pokemon.jpg\",\"datePublished\":\"2022-09-16T00:04:05+00:00\",\"dateModified\":\"2026-01-05T19:48:24+00:00\",\"description\":\"Funko Squirtle 25cm (Pok\u00e9mon) (#505): Licencia: Pok\u00e9mon. L\u00ednea de funkos: Pok\u00e9mon. N\u00famero: 505\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-squirtle-10-25-cm-pokemon.jpg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-squirtle-10-25-cm-pokemon.jpg\",\"width\":600,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FUNKO POP! 10&#8243; POKEMON &#8211; LAPRAS 10&#8243; 25CM (EMEA)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funko Squirtle 25cm (Pok\u00e9mon) (#505) | Colossal Store","description":"Funko Squirtle 25cm (Pok\u00e9mon) (#505): Licencia: Pok\u00e9mon. L\u00ednea de funkos: Pok\u00e9mon. N\u00famero: 505","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/","og_locale":"en_US","og_type":"article","og_title":"Funko Squirtle 25cm (Pok\u00e9mon) (#505) | Colossal Store","og_description":"Funko Squirtle 25cm (Pok\u00e9mon) (#505): Licencia: Pok\u00e9mon. L\u00ednea de funkos: Pok\u00e9mon. N\u00famero: 505","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/","og_site_name":"Colossal Store","article_modified_time":"2026-01-05T19:48:24+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-squirtle-10-25-cm-pokemon.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/","url":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/","name":"Funko Squirtle 25cm (Pok\u00e9mon) (#505) | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-squirtle-10-25-cm-pokemon.jpg","datePublished":"2022-09-16T00:04:05+00:00","dateModified":"2026-01-05T19:48:24+00:00","description":"Funko Squirtle 25cm (Pok\u00e9mon) (#505): Licencia: Pok\u00e9mon. L\u00ednea de funkos: Pok\u00e9mon. N\u00famero: 505","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-squirtle-10-25-cm-pokemon.jpg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-squirtle-10-25-cm-pokemon.jpg","width":600,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-squirtle-10-25-cm-pokemon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"FUNKO POP! 10&#8243; POKEMON &#8211; LAPRAS 10&#8243; 25CM (EMEA)"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/558"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=557"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=557"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=557"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}