{"id":551,"date":"2022-09-16T02:01:27","date_gmt":"2022-09-16T00:01:27","guid":{"rendered":"https:\/\/colossalstore.es\/?post_type=product&#038;p=551"},"modified":"2025-06-20T11:21:46","modified_gmt":"2025-06-20T09:21:46","slug":"funko-pop-1176-ed-fullmetal-alchemist","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/","title":{"rendered":"Funko POP! 1176 Ed Fullmetal Alchemist"},"content":{"rendered":"<p>Funko Edward Elric (Fullmetal Alchemist) (#1176)<\/p>\n<p>DATA SHEET:<\/p>\n<p>License: Fullmetal Alchemist<\/p>\n<p>Funko line: Fullmetal Alchemist<\/p>\n<p>Number: 1176<\/p>","protected":false},"excerpt":{"rendered":"<p>Funko Edward Elric (Fullmetal Alchemist) (#1176) FICHA T\u00c9CNICA: Licencia: Fullmetal Alchemist L\u00ednea de funkos: Fullmetal Alchemist N\u00famero: 1176<\/p>","protected":false},"featured_media":552,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[20],"product_tag":[],"class_list":{"0":"post-551","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-funkos","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Funko Edward Elric (Fullmetal Alchemist) (#1176) | Colossal Store<\/title>\n<meta name=\"description\" content=\"Funko Edward Elric (Fullmetal Alchemist) (#1176): Licencia: Fullmetal Alchemist. L\u00ednea de funkos: Fullmetal Alchemist. N\u00famero: 1176\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funko Edward Elric (Fullmetal Alchemist) (#1176) | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Funko Edward Elric (Fullmetal Alchemist) (#1176): Licencia: Fullmetal Alchemist. L\u00ednea de funkos: Fullmetal Alchemist. N\u00famero: 1176\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:21:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-1176-ed-fullmetal-alchemist.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/\",\"name\":\"Funko Edward Elric (Fullmetal Alchemist) (#1176) | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-1176-ed-fullmetal-alchemist.jpg\",\"datePublished\":\"2022-09-16T00:01:27+00:00\",\"dateModified\":\"2025-06-20T09:21:46+00:00\",\"description\":\"Funko Edward Elric (Fullmetal Alchemist) (#1176): Licencia: Fullmetal Alchemist. L\u00ednea de funkos: Fullmetal Alchemist. N\u00famero: 1176\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-1176-ed-fullmetal-alchemist.jpg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-1176-ed-fullmetal-alchemist.jpg\",\"width\":600,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Funko POP! 1176 Ed Fullmetal Alchemist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funko Edward Elric (Fullmetal Alchemist) (#1176) | Colossal Store","description":"Funko Edward Elric (Fullmetal Alchemist) (#1176): Licencia: Fullmetal Alchemist. L\u00ednea de funkos: Fullmetal Alchemist. N\u00famero: 1176","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/","og_locale":"en_US","og_type":"article","og_title":"Funko Edward Elric (Fullmetal Alchemist) (#1176) | Colossal Store","og_description":"Funko Edward Elric (Fullmetal Alchemist) (#1176): Licencia: Fullmetal Alchemist. L\u00ednea de funkos: Fullmetal Alchemist. N\u00famero: 1176","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:21:46+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-1176-ed-fullmetal-alchemist.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/","url":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/","name":"Funko Edward Elric (Fullmetal Alchemist) (#1176) | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-1176-ed-fullmetal-alchemist.jpg","datePublished":"2022-09-16T00:01:27+00:00","dateModified":"2025-06-20T09:21:46+00:00","description":"Funko Edward Elric (Fullmetal Alchemist) (#1176): Licencia: Fullmetal Alchemist. L\u00ednea de funkos: Fullmetal Alchemist. N\u00famero: 1176","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-1176-ed-fullmetal-alchemist.jpg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-1176-ed-fullmetal-alchemist.jpg","width":600,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-1176-ed-fullmetal-alchemist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Funko POP! 1176 Ed Fullmetal Alchemist"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/552"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=551"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=551"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=551"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}