{"id":5117,"date":"2023-05-26T18:04:09","date_gmt":"2023-05-26T16:04:09","guid":{"rendered":"https:\/\/www.colossalstore.es\/?post_type=product&#038;p=5117"},"modified":"2025-06-20T11:15:48","modified_gmt":"2025-06-20T09:15:48","slug":"gamegenic-deck-holder-80-orange","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/","title":{"rendered":"Gamegenic \u2013 Deck Holder 80+ Orange"},"content":{"rendered":"<p>Gamegenic \u2013 Deck Holder 80+ Orange<\/p>\n<p>This product offers players a smart and quick solution to store and organize their decks of cards. The Deck Holder 80+ is a basic deck box that guarantees the protection of up to 80 cards with a double sleeve.<\/p>","protected":false},"excerpt":{"rendered":"<p>Gamegenic &#8211; Deck Holder 80+ Orange Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 80+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 80 cartas con doble funda.<\/p>","protected":false},"featured_media":5118,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[35,34],"product_tag":[],"class_list":{"0":"post-5117","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accesorios","7":"product_cat-tcg","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gamegenic - Deck Holder 80+ Orange | Colossal Store<\/title>\n<meta name=\"description\" content=\"Gamegenic - Deck Holder 80+ Yellow: Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 80+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 80 cartas con doble funda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gamegenic - Deck Holder 80+ Orange | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Gamegenic - Deck Holder 80+ Yellow: Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 80+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 80 cartas con doble funda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:15:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/cajas-de-mazos-80-naranja-gamegenic.png\" \/>\n\t<meta property=\"og:image:width\" content=\"452\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/\",\"name\":\"Gamegenic - Deck Holder 80+ Orange | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/cajas-de-mazos-80-naranja-gamegenic.png\",\"datePublished\":\"2023-05-26T16:04:09+00:00\",\"dateModified\":\"2025-06-20T09:15:48+00:00\",\"description\":\"Gamegenic - Deck Holder 80+ Yellow: Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 80+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 80 cartas con doble funda.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/cajas-de-mazos-80-naranja-gamegenic.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/cajas-de-mazos-80-naranja-gamegenic.png\",\"width\":452,\"height\":452},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gamegenic &#8211; Deck Holder 80+ Orange\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gamegenic - Deck Holder 80+ Orange | Colossal Store","description":"Gamegenic - Deck Holder 80+ Yellow: Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 80+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 80 cartas con doble funda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/","og_locale":"en_US","og_type":"article","og_title":"Gamegenic - Deck Holder 80+ Orange | Colossal Store","og_description":"Gamegenic - Deck Holder 80+ Yellow: Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 80+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 80 cartas con doble funda.","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:15:48+00:00","og_image":[{"width":452,"height":452,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/cajas-de-mazos-80-naranja-gamegenic.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/","url":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/","name":"Gamegenic - Deck Holder 80+ Orange | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/cajas-de-mazos-80-naranja-gamegenic.png","datePublished":"2023-05-26T16:04:09+00:00","dateModified":"2025-06-20T09:15:48+00:00","description":"Gamegenic - Deck Holder 80+ Yellow: Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 80+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 80 cartas con doble funda.","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/cajas-de-mazos-80-naranja-gamegenic.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/cajas-de-mazos-80-naranja-gamegenic.png","width":452,"height":452},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-80-orange\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Gamegenic &#8211; Deck Holder 80+ Orange"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/5117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=5117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/5118"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=5117"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=5117"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=5117"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=5117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}