{"id":4813,"date":"2023-04-20T20:01:48","date_gmt":"2023-04-20T18:01:48","guid":{"rendered":"https:\/\/www.colossalstore.es\/?post_type=product&#038;p=4813"},"modified":"2025-06-20T11:17:56","modified_gmt":"2025-06-20T09:17:56","slug":"guardianes-de-la-noche-20","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/guardianes-de-la-noche-20\/","title":{"rendered":"Night Watch 20"},"content":{"rendered":"<p>Kimetsu no Yaiba 20 (Koyoharu Gotouge)<\/p>\n<p>THE DEFINITIVE BATTLE AGAINST THE FIRST SUPERIOR MOONThe Himejima and Shinazugawa pillars face the first Superior Moon. In the course of the fight, both develop marks on their skin, but neither these nor their coordination in the attack are enough to overshadow the overwhelming power of the enemy. However, when everything seems lost, Genya recovers by absorbing a part of the first moon... What will be the outcome of this bloody battle...?!<\/p>","protected":false},"excerpt":{"rendered":"<p>Kimetsu no Yaiba 20 (Koyoharu Gotouge) LA BATALLA DEFINITIVA CONTRA LA PRIMERA LUNA SUPERIORos pilares Himejima y Shinazugawa se enfrentan a la primera Luna superior. En el transcursoe la pelea, ambos desarrollan las marcas en su piel, pero ni estas ni su coordinaci\u00f3n en eltaque son suficientes para hacer sombra al abrumador poder del enemigo. [&hellip;]<\/p>","protected":false},"featured_media":4814,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[32],"product_tag":[],"class_list":{"0":"post-4813","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-manga","8":"first","9":"outofstock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kimetsu no Yaiba 20 (Koyoharu Gotouge) | Colossal Store<\/title>\n<meta name=\"description\" content=\"Kimetsu no Yaiba 20 (Koyoharu Gotouge): LA BATALLA DEFINITIVA CONTRA LA PRIMERA LUNA SUPERIORos pilares Himejima y Shinazugawa se enfrentan a la primera Luna superior. En el transcursoe la pelea, ambos desarrollan las marcas en su piel, pero ni estas ni su coordinaci\u00f3n en eltaque son suficientes para hacer sombra al abrumador poder del enemigo. Sin embargo,uando todo parece perdido, Genya se recupera absorbiendo una parte de la primerauna... \u00a1\u00bfCu\u00e1l ser\u00e1 el desenlace de esta cruenta batalla...?!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/guardianes-de-la-noche-20\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kimetsu no Yaiba 20 (Koyoharu Gotouge) | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Kimetsu no Yaiba 20 (Koyoharu Gotouge): LA BATALLA DEFINITIVA CONTRA LA PRIMERA LUNA SUPERIORos pilares Himejima y Shinazugawa se enfrentan a la primera Luna superior. En el transcursoe la pelea, ambos desarrollan las marcas en su piel, pero ni estas ni su coordinaci\u00f3n en eltaque son suficientes para hacer sombra al abrumador poder del enemigo. Sin embargo,uando todo parece perdido, Genya se recupera absorbiendo una parte de la primerauna... \u00a1\u00bfCu\u00e1l ser\u00e1 el desenlace de esta cruenta batalla...?!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/guardianes-de-la-noche-20\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:17:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/04\/9788467944839.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"552\" \/>\n\t<meta property=\"og:image:height\" content=\"840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/\",\"name\":\"Kimetsu no Yaiba 20 (Koyoharu Gotouge) | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/04\/9788467944839.jpg\",\"datePublished\":\"2023-04-20T18:01:48+00:00\",\"dateModified\":\"2025-06-20T09:17:56+00:00\",\"description\":\"Kimetsu no Yaiba 20 (Koyoharu Gotouge): LA BATALLA DEFINITIVA CONTRA LA PRIMERA LUNA SUPERIORos pilares Himejima y Shinazugawa se enfrentan a la primera Luna superior. En el transcursoe la pelea, ambos desarrollan las marcas en su piel, pero ni estas ni su coordinaci\u00f3n en eltaque son suficientes para hacer sombra al abrumador poder del enemigo. Sin embargo,uando todo parece perdido, Genya se recupera absorbiendo una parte de la primerauna... \u00a1\u00bfCu\u00e1l ser\u00e1 el desenlace de esta cruenta batalla...?!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/04\/9788467944839.jpg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/04\/9788467944839.jpg\",\"width\":552,\"height\":840},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Guardianes de la noche 20\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kimetsu no Yaiba 20 (Koyoharu Gotouge) | Colossal Store","description":"Kimetsu no Yaiba 20 (Koyoharu Gotouge): LA BATALLA DEFINITIVA CONTRA LA PRIMERA LUNA SUPERIORos pilares Himejima y Shinazugawa se enfrentan a la primera Luna superior. En el transcursoe la pelea, ambos desarrollan las marcas en su piel, pero ni estas ni su coordinaci\u00f3n en eltaque son suficientes para hacer sombra al abrumador poder del enemigo. Sin embargo,uando todo parece perdido, Genya se recupera absorbiendo una parte de la primerauna... \u00a1\u00bfCu\u00e1l ser\u00e1 el desenlace de esta cruenta batalla...?!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/guardianes-de-la-noche-20\/","og_locale":"en_US","og_type":"article","og_title":"Kimetsu no Yaiba 20 (Koyoharu Gotouge) | Colossal Store","og_description":"Kimetsu no Yaiba 20 (Koyoharu Gotouge): LA BATALLA DEFINITIVA CONTRA LA PRIMERA LUNA SUPERIORos pilares Himejima y Shinazugawa se enfrentan a la primera Luna superior. En el transcursoe la pelea, ambos desarrollan las marcas en su piel, pero ni estas ni su coordinaci\u00f3n en eltaque son suficientes para hacer sombra al abrumador poder del enemigo. Sin embargo,uando todo parece perdido, Genya se recupera absorbiendo una parte de la primerauna... \u00a1\u00bfCu\u00e1l ser\u00e1 el desenlace de esta cruenta batalla...?!","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/manga\/guardianes-de-la-noche-20\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:17:56+00:00","og_image":[{"width":552,"height":840,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/04\/9788467944839.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/","url":"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/","name":"Kimetsu no Yaiba 20 (Koyoharu Gotouge) | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/04\/9788467944839.jpg","datePublished":"2023-04-20T18:01:48+00:00","dateModified":"2025-06-20T09:17:56+00:00","description":"Kimetsu no Yaiba 20 (Koyoharu Gotouge): LA BATALLA DEFINITIVA CONTRA LA PRIMERA LUNA SUPERIORos pilares Himejima y Shinazugawa se enfrentan a la primera Luna superior. En el transcursoe la pelea, ambos desarrollan las marcas en su piel, pero ni estas ni su coordinaci\u00f3n en eltaque son suficientes para hacer sombra al abrumador poder del enemigo. Sin embargo,uando todo parece perdido, Genya se recupera absorbiendo una parte de la primerauna... \u00a1\u00bfCu\u00e1l ser\u00e1 el desenlace de esta cruenta batalla...?!","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/04\/9788467944839.jpg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/04\/9788467944839.jpg","width":552,"height":840},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/manga\/guardianes-de-la-noche-20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Guardianes de la noche 20"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/4813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=4813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/4814"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=4813"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=4813"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=4813"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=4813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}