{"id":402,"date":"2022-09-15T16:05:05","date_gmt":"2022-09-15T14:05:05","guid":{"rendered":"https:\/\/colossalstore.es\/?post_type=product&#038;p=402"},"modified":"2025-06-20T11:21:49","modified_gmt":"2025-06-20T09:21:49","slug":"funko-pop-babu-frik-10-25-cm-star-wars","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/","title":{"rendered":"Funko POP! Babu Frik 10\u2033 25 Cm \u2013 Star Wars"},"content":{"rendered":"<p>Funko Babu Frik 25cm (Star Wars) (#435)<\/p>\n<p>DATA SHEET:<\/p>\n<p>License: Star Wars<\/p>\n<p>Funko line: Star Wars<\/p>\n<p>Number: 435<\/p>","protected":false},"excerpt":{"rendered":"<p>Funko Babu Frik 25cm (Star Wars) (#435) FICHA T\u00c9CNICA: Licencia: Star Wars L\u00ednea de funkos: Star Wars N\u00famero: 435<\/p>","protected":false},"featured_media":403,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[20],"product_tag":[],"class_list":{"0":"post-402","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-funkos","8":"first","9":"outofstock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Funko Babu Frik 25cm (Star Wars) (#435) | Colossal Store<\/title>\n<meta name=\"description\" content=\"Funko Babu Frik 25cm (Star Wars) (#435): Licencia: Star Wars. L\u00ednea de funkos: Star Wars. N\u00famero: 435\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funko Babu Frik 25cm (Star Wars) (#435) | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Funko Babu Frik 25cm (Star Wars) (#435): Licencia: Star Wars. L\u00ednea de funkos: Star Wars. N\u00famero: 435\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:21:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-babu-frik-10-25-cm-star-wars.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/\",\"name\":\"Funko Babu Frik 25cm (Star Wars) (#435) | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-babu-frik-10-25-cm-star-wars.jpg\",\"datePublished\":\"2022-09-15T14:05:05+00:00\",\"dateModified\":\"2025-06-20T09:21:49+00:00\",\"description\":\"Funko Babu Frik 25cm (Star Wars) (#435): Licencia: Star Wars. L\u00ednea de funkos: Star Wars. N\u00famero: 435\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-babu-frik-10-25-cm-star-wars.jpg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-babu-frik-10-25-cm-star-wars.jpg\",\"width\":600,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Funko POP! Babu Frik 10&#8243; 25 Cm &#8211; Star Wars\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funko Babu Frik 25cm (Star Wars) (#435) | Colossal Store","description":"Funko Babu Frik 25cm (Star Wars) (#435): Licencia: Star Wars. L\u00ednea de funkos: Star Wars. N\u00famero: 435","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/","og_locale":"en_US","og_type":"article","og_title":"Funko Babu Frik 25cm (Star Wars) (#435) | Colossal Store","og_description":"Funko Babu Frik 25cm (Star Wars) (#435): Licencia: Star Wars. L\u00ednea de funkos: Star Wars. N\u00famero: 435","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:21:49+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-babu-frik-10-25-cm-star-wars.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/","url":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/","name":"Funko Babu Frik 25cm (Star Wars) (#435) | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-babu-frik-10-25-cm-star-wars.jpg","datePublished":"2022-09-15T14:05:05+00:00","dateModified":"2025-06-20T09:21:49+00:00","description":"Funko Babu Frik 25cm (Star Wars) (#435): Licencia: Star Wars. L\u00ednea de funkos: Star Wars. N\u00famero: 435","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-babu-frik-10-25-cm-star-wars.jpg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/09\/funko-pop-babu-frik-10-25-cm-star-wars.jpg","width":600,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/funkos\/funko-pop-babu-frik-10-25-cm-star-wars\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Funko POP! Babu Frik 10&#8243; 25 Cm &#8211; Star Wars"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/403"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=402"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=402"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=402"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}