{"id":3734,"date":"2023-01-23T19:09:20","date_gmt":"2023-01-23T18:09:20","guid":{"rendered":"https:\/\/www.colossalstore.es\/?post_type=product&#038;p=3734"},"modified":"2025-06-20T11:18:04","modified_gmt":"2025-06-20T09:18:04","slug":"gamegenic-deck-holder-100-white","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/","title":{"rendered":"Gamegenic \u2013 Deck Holder 100+ White"},"content":{"rendered":"<p>Gamegenic \u2013 Deck Holder 100+ White<\/p>\n<p>This product offers players a smart and quick solution for storing and organizing their decks of cards. The Deck Holder 100+ is a basic deck box that guarantees the protection of up to 100 double-sleeved cards.<\/p>","protected":false},"excerpt":{"rendered":"<p>Gamegenic &#8211; Deck Holder 100+ White Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 100+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 100 cartas con doble funda.<\/p>","protected":false},"featured_media":3735,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[35],"product_tag":[],"class_list":{"0":"post-3734","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accesorios","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gamegenic - Deck Holder 100+ White | Colossal Store<\/title>\n<meta name=\"description\" content=\"Gamegenic - Deck Holder 100+ White: Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 100+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 100 cartas con doble funda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gamegenic - Deck Holder 100+ White | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Gamegenic - Deck Holder 100+ White: Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 100+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 100 cartas con doble funda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:18:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/asda.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/\",\"name\":\"Gamegenic - Deck Holder 100+ White | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/asda.jpg\",\"datePublished\":\"2023-01-23T18:09:20+00:00\",\"dateModified\":\"2025-06-20T09:18:04+00:00\",\"description\":\"Gamegenic - Deck Holder 100+ White: Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 100+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 100 cartas con doble funda.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/asda.jpg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/asda.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gamegenic &#8211; Deck Holder 100+ White\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gamegenic - Deck Holder 100+ White | Colossal Store","description":"Gamegenic - Deck Holder 100+ White: Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 100+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 100 cartas con doble funda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/","og_locale":"en_US","og_type":"article","og_title":"Gamegenic - Deck Holder 100+ White | Colossal Store","og_description":"Gamegenic - Deck Holder 100+ White: Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 100+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 100 cartas con doble funda.","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:18:04+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/asda.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/","url":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/","name":"Gamegenic - Deck Holder 100+ White | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/asda.jpg","datePublished":"2023-01-23T18:09:20+00:00","dateModified":"2025-06-20T09:18:04+00:00","description":"Gamegenic - Deck Holder 100+ White: Este producto ofrece a los jugadores una soluci\u00f3n inteligente y r\u00e1pida para almacenar y organizar sus mazos de cartas. El Deck Holder 100+ es una caja para mazos b\u00e1sica que garantiza la protecci\u00f3n de hasta 100 cartas con doble funda.","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/asda.jpg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/asda.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-deck-holder-100-white\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Gamegenic &#8211; Deck Holder 100+ White"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/3734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=3734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/3735"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=3734"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=3734"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=3734"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=3734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}