{"id":3635,"date":"2023-01-19T13:44:39","date_gmt":"2023-01-19T12:44:39","guid":{"rendered":"https:\/\/www.colossalstore.es\/?post_type=product&#038;p=3635"},"modified":"2025-06-20T11:18:05","modified_gmt":"2025-06-20T09:18:05","slug":"pokemon-cenit-supremo-regidrago-v-es","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/","title":{"rendered":"Pok\u00e9mon \u2013 Supreme Zenith \u2013 Regidrago V \u2013 EN"},"content":{"rendered":"<p>Pok\u00e9mon TCG Regidrago V \u2013 Supreme Peak \u2013 EN<\/p>\n<p>March 2023 collection of the Pokemon TCG card game. Spanish.<\/p>\n<p>The Pokemon TCG: Ultimate Peak Regieleki V or Regidrago V Collection contains:<\/p>\n<p>\u2013 1 holographic promo card for Regieleki V or Regidrago V<\/p>\n<p>\u2013 1 holographic promotion card of Regieleki or Regidrago<\/p>\n<p>\u2013 1 oversized foil card of Regieleki V or Regidrago V<\/p>\n<p>\u2013 4 Pok\u00e9mon TCG: Ultimate Peak Booster Packs<\/p>\n<p>\u2013 1 code card for Pok\u00e9mon TCG Live<\/p>\n<p>(Letters may vary depending on the package)<\/p>","protected":false},"excerpt":{"rendered":"<p>Pok\u00e9mon TCG Regidrago V &#8211; Cenit Supremo &#8211; ES Colecci\u00f3n Marzo 2023 del juego de cartas Pokemon TCG. Espa\u00f1ol. La colecci\u00f3n Regieleki V o Regidrago V de Cenit Supremo de JCC Pokemon contiene: &#8211; 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki V o Regidrago V &#8211; 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki\u00a0 o Regidrago [&hellip;]<\/p>","protected":false},"featured_media":3636,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[49,34],"product_tag":[],"class_list":{"0":"post-3635","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pokemon","7":"product_cat-tcg","9":"first","10":"outofstock","11":"sale","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pok\u00e9mon TCG Regidrago V - Cenit Supremo - ES | Colossal Store<\/title>\n<meta name=\"description\" content=\"Pok\u00e9mon TCG Regidrago V - Cenit Supremo - ES: Colecci\u00f3n Marzo 2023 del juego de cartas Pokemon TCG. Espa\u00f1ol.La colecci\u00f3n Regieleki V o Regidrago V de Cenit Supremo de JCC Pokemon contiene:- 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki V o Regidrago V- 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki\u00a0 o Regidrago- 1 carta hologr\u00e1fica de\u00a0gran tama\u00f1o de Regieleki V o Regidrago V- 4 paquetes de mejora de Cenit Supremo de JCC Pok\u00e9mon- 1 carta con c\u00f3digo para JCC Pok\u00e9mon Live(Las cartas pueden variar en funci\u00f3n del paquete)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pok\u00e9mon TCG Regidrago V - Cenit Supremo - ES | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Pok\u00e9mon TCG Regidrago V - Cenit Supremo - ES: Colecci\u00f3n Marzo 2023 del juego de cartas Pokemon TCG. Espa\u00f1ol.La colecci\u00f3n Regieleki V o Regidrago V de Cenit Supremo de JCC Pokemon contiene:- 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki V o Regidrago V- 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki\u00a0 o Regidrago- 1 carta hologr\u00e1fica de\u00a0gran tama\u00f1o de Regieleki V o Regidrago V- 4 paquetes de mejora de Cenit Supremo de JCC Pok\u00e9mon- 1 carta con c\u00f3digo para JCC Pok\u00e9mon Live(Las cartas pueden variar en funci\u00f3n del paquete)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:18:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/683011.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/\",\"name\":\"Pok\u00e9mon TCG Regidrago V - Cenit Supremo - ES | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/683011.jpg\",\"datePublished\":\"2023-01-19T12:44:39+00:00\",\"dateModified\":\"2025-06-20T09:18:05+00:00\",\"description\":\"Pok\u00e9mon TCG Regidrago V - Cenit Supremo - ES: Colecci\u00f3n Marzo 2023 del juego de cartas Pokemon TCG. Espa\u00f1ol.La colecci\u00f3n Regieleki V o Regidrago V de Cenit Supremo de JCC Pokemon contiene:- 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki V o Regidrago V- 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki\u00a0 o Regidrago- 1 carta hologr\u00e1fica de\u00a0gran tama\u00f1o de Regieleki V o Regidrago V- 4 paquetes de mejora de Cenit Supremo de JCC Pok\u00e9mon- 1 carta con c\u00f3digo para JCC Pok\u00e9mon Live(Las cartas pueden variar en funci\u00f3n del paquete)\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/683011.jpg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/683011.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pok\u00e9mon &#8211; Cenit Supremo &#8211; Regidrago V &#8211; ES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pok\u00e9mon TCG Regidrago V - Cenit Supremo - ES | Colossal Store","description":"Pok\u00e9mon TCG Regidrago V - Cenit Supremo - ES: Colecci\u00f3n Marzo 2023 del juego de cartas Pokemon TCG. Espa\u00f1ol.La colecci\u00f3n Regieleki V o Regidrago V de Cenit Supremo de JCC Pokemon contiene:- 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki V o Regidrago V- 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki\u00a0 o Regidrago- 1 carta hologr\u00e1fica de\u00a0gran tama\u00f1o de Regieleki V o Regidrago V- 4 paquetes de mejora de Cenit Supremo de JCC Pok\u00e9mon- 1 carta con c\u00f3digo para JCC Pok\u00e9mon Live(Las cartas pueden variar en funci\u00f3n del paquete)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/","og_locale":"en_US","og_type":"article","og_title":"Pok\u00e9mon TCG Regidrago V - Cenit Supremo - ES | Colossal Store","og_description":"Pok\u00e9mon TCG Regidrago V - Cenit Supremo - ES: Colecci\u00f3n Marzo 2023 del juego de cartas Pokemon TCG. Espa\u00f1ol.La colecci\u00f3n Regieleki V o Regidrago V de Cenit Supremo de JCC Pokemon contiene:- 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki V o Regidrago V- 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki\u00a0 o Regidrago- 1 carta hologr\u00e1fica de\u00a0gran tama\u00f1o de Regieleki V o Regidrago V- 4 paquetes de mejora de Cenit Supremo de JCC Pok\u00e9mon- 1 carta con c\u00f3digo para JCC Pok\u00e9mon Live(Las cartas pueden variar en funci\u00f3n del paquete)","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:18:05+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/683011.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/","url":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/","name":"Pok\u00e9mon TCG Regidrago V - Cenit Supremo - ES | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/683011.jpg","datePublished":"2023-01-19T12:44:39+00:00","dateModified":"2025-06-20T09:18:05+00:00","description":"Pok\u00e9mon TCG Regidrago V - Cenit Supremo - ES: Colecci\u00f3n Marzo 2023 del juego de cartas Pokemon TCG. Espa\u00f1ol.La colecci\u00f3n Regieleki V o Regidrago V de Cenit Supremo de JCC Pokemon contiene:- 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki V o Regidrago V- 1 carta hologr\u00e1fica de promoci\u00f3n de Regieleki\u00a0 o Regidrago- 1 carta hologr\u00e1fica de\u00a0gran tama\u00f1o de Regieleki V o Regidrago V- 4 paquetes de mejora de Cenit Supremo de JCC Pok\u00e9mon- 1 carta con c\u00f3digo para JCC Pok\u00e9mon Live(Las cartas pueden variar en funci\u00f3n del paquete)","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/683011.jpg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/01\/683011.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/pokemon-cenit-supremo-regidrago-v-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Pok\u00e9mon &#8211; Cenit Supremo &#8211; Regidrago V &#8211; ES"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/3635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=3635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/3636"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=3635"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=3635"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=3635"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=3635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}