{"id":2558,"date":"2022-10-29T12:10:58","date_gmt":"2022-10-29T10:10:58","guid":{"rendered":"https:\/\/www.colossalstore.es\/?post_type=product&#038;p=2558"},"modified":"2025-06-20T11:19:15","modified_gmt":"2025-06-20T09:19:15","slug":"gamegenic-side-holder-100-xl-green","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/","title":{"rendered":"Gamegenic \u2013 Side Holder 100+ XL Green"},"content":{"rendered":"<p>Gamegenic \u2013 Side Holder 100+ XL Green<\/p>\n<p>Inside they fit up to 100 double-sleeved cards with thick inner sleeves. Heavy-duty deck box with self-closing lid and writing strip. Side Loading: Cards are stored horizontally.<\/p>","protected":false},"excerpt":{"rendered":"<p>Gamegenic &#8211; Side Holder 100+ XL Green Dentro caben hasta\u00a0100\u00a0cartas en doble funda con\u00a0fundas interiores gruesas.\u00a0Caja resistente para mazos con tapa con autocierre y tira para escribir.\u00a0Carga lateral: las cartas se almacenan horizontalmente.<\/p>","protected":false},"featured_media":2564,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[35],"product_tag":[],"class_list":{"0":"post-2558","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accesorios","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gamegenic - Side Holder 100+ XL Green | Colossal Store<\/title>\n<meta name=\"description\" content=\"Gamegenic - Side Holder 100+ XL Green: Dentro caben hasta\u00a0100\u00a0cartas en doble funda con\u00a0fundas interiores gruesas.\u00a0Caja resistente para mazos con tapa con autocierre y tira para escribir.\u00a0Carga lateral: las cartas se almacenan horizontalmente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gamegenic - Side Holder 100+ XL Green | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Gamegenic - Side Holder 100+ XL Green: Dentro caben hasta\u00a0100\u00a0cartas en doble funda con\u00a0fundas interiores gruesas.\u00a0Caja resistente para mazos con tapa con autocierre y tira para escribir.\u00a0Carga lateral: las cartas se almacenan horizontalmente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:19:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/comprar-side-holder-100-xl-green-barato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"458\" \/>\n\t<meta property=\"og:image:height\" content=\"458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/\",\"name\":\"Gamegenic - Side Holder 100+ XL Green | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/comprar-side-holder-100-xl-green-barato.jpg\",\"datePublished\":\"2022-10-29T10:10:58+00:00\",\"dateModified\":\"2025-06-20T09:19:15+00:00\",\"description\":\"Gamegenic - Side Holder 100+ XL Green: Dentro caben hasta\u00a0100\u00a0cartas en doble funda con\u00a0fundas interiores gruesas.\u00a0Caja resistente para mazos con tapa con autocierre y tira para escribir.\u00a0Carga lateral: las cartas se almacenan horizontalmente.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/comprar-side-holder-100-xl-green-barato.jpg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/comprar-side-holder-100-xl-green-barato.jpg\",\"width\":458,\"height\":458},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gamegenic &#8211; Side Holder 100+ XL Green\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gamegenic - Side Holder 100+ XL Green | Colossal Store","description":"Gamegenic - Side Holder 100+ XL Green: Dentro caben hasta\u00a0100\u00a0cartas en doble funda con\u00a0fundas interiores gruesas.\u00a0Caja resistente para mazos con tapa con autocierre y tira para escribir.\u00a0Carga lateral: las cartas se almacenan horizontalmente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/","og_locale":"en_US","og_type":"article","og_title":"Gamegenic - Side Holder 100+ XL Green | Colossal Store","og_description":"Gamegenic - Side Holder 100+ XL Green: Dentro caben hasta\u00a0100\u00a0cartas en doble funda con\u00a0fundas interiores gruesas.\u00a0Caja resistente para mazos con tapa con autocierre y tira para escribir.\u00a0Carga lateral: las cartas se almacenan horizontalmente.","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:19:15+00:00","og_image":[{"width":458,"height":458,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/comprar-side-holder-100-xl-green-barato.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/","url":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/","name":"Gamegenic - Side Holder 100+ XL Green | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/comprar-side-holder-100-xl-green-barato.jpg","datePublished":"2022-10-29T10:10:58+00:00","dateModified":"2025-06-20T09:19:15+00:00","description":"Gamegenic - Side Holder 100+ XL Green: Dentro caben hasta\u00a0100\u00a0cartas en doble funda con\u00a0fundas interiores gruesas.\u00a0Caja resistente para mazos con tapa con autocierre y tira para escribir.\u00a0Carga lateral: las cartas se almacenan horizontalmente.","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/comprar-side-holder-100-xl-green-barato.jpg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/comprar-side-holder-100-xl-green-barato.jpg","width":458,"height":458},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/accesorios\/gamegenic-side-holder-100-xl-green\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Gamegenic &#8211; Side Holder 100+ XL Green"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/2558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=2558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/2564"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=2558"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=2558"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=2558"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=2558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}