{"id":2176,"date":"2022-10-18T18:27:13","date_gmt":"2022-10-18T16:27:13","guid":{"rendered":"https:\/\/colossalstore.es\/?post_type=product&#038;p=2176"},"modified":"2025-06-20T11:19:17","modified_gmt":"2025-06-20T09:19:17","slug":"el-asombroso-spiderman-3-spiderman-v2-211","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/","title":{"rendered":"The Amazing Spiderman 3 (SPIDERMAN V2 211)"},"content":{"rendered":"<p>The Amazing Spiderman 3 (SPIDERMAN V2 211)<\/p>\n<p>DATA SHEET:<\/p>\n<p>License: Marvel<\/p>\n<p>Series: Spiderman<\/p>","protected":false},"excerpt":{"rendered":"<p>The Amazing Spiderman 3 (SPIDERMAN V2 211) TECHNICAL SHEET: License: Marvel Series: Spiderman<\/p>","protected":false},"featured_media":2177,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[33],"product_tag":[],"class_list":{"0":"post-2176","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-comics","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Asombroso Spiderman 3 (SPIDERMAN V2 211) | Colossal Store<\/title>\n<meta name=\"description\" content=\"El Asombroso Spiderman 3 (SPIDERMAN V2 211): FICHA T\u00c9CNICA: Licencia: Marvel. Serie: Spiderman\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Asombroso Spiderman 3 (SPIDERMAN V2 211) | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"El Asombroso Spiderman 3 (SPIDERMAN V2 211): FICHA T\u00c9CNICA: Licencia: Marvel. Serie: Spiderman\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T09:19:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/spide211_0-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"781\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/\",\"name\":\"El Asombroso Spiderman 3 (SPIDERMAN V2 211) | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/spide211_0-1.webp\",\"datePublished\":\"2022-10-18T16:27:13+00:00\",\"dateModified\":\"2025-06-20T09:19:17+00:00\",\"description\":\"El Asombroso Spiderman 3 (SPIDERMAN V2 211): FICHA T\u00c9CNICA: Licencia: Marvel. Serie: Spiderman\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/spide211_0-1.webp\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/spide211_0-1.webp\",\"width\":781,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El Asombroso Spiderman 3 (SPIDERMAN V2 211)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Asombroso Spiderman 3 (SPIDERMAN V2 211) | Colossal Store","description":"El Asombroso Spiderman 3 (SPIDERMAN V2 211): FICHA T\u00c9CNICA: Licencia: Marvel. Serie: Spiderman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/","og_locale":"en_US","og_type":"article","og_title":"El Asombroso Spiderman 3 (SPIDERMAN V2 211) | Colossal Store","og_description":"El Asombroso Spiderman 3 (SPIDERMAN V2 211): FICHA T\u00c9CNICA: Licencia: Marvel. Serie: Spiderman","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/","og_site_name":"Colossal Store","article_modified_time":"2025-06-20T09:19:17+00:00","og_image":[{"width":781,"height":1200,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/spide211_0-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/","url":"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/","name":"El Asombroso Spiderman 3 (SPIDERMAN V2 211) | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/spide211_0-1.webp","datePublished":"2022-10-18T16:27:13+00:00","dateModified":"2025-06-20T09:19:17+00:00","description":"El Asombroso Spiderman 3 (SPIDERMAN V2 211): FICHA T\u00c9CNICA: Licencia: Marvel. Serie: Spiderman","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/spide211_0-1.webp","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2022\/10\/spide211_0-1.webp","width":781,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/comics\/el-asombroso-spiderman-3-spiderman-v2-211\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"El Asombroso Spiderman 3 (SPIDERMAN V2 211)"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/2176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=2176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/2177"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=2176"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=2176"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=2176"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=2176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}