{"id":11118,"date":"2025-07-25T14:10:30","date_gmt":"2025-07-25T12:10:30","guid":{"rendered":"https:\/\/www.colossalstore.es\/?post_type=product&#038;p=11118"},"modified":"2025-08-05T19:43:53","modified_gmt":"2025-08-05T17:43:53","slug":"charizard-ex-special-collection-en","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/","title":{"rendered":"CHARIZARD EX SPECIAL COLLECTION &#8211; EN"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":11120,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[49,34],"product_tag":[],"class_list":{"0":"post-11118","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pokemon","7":"product_cat-tcg","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CHARIZARD EX SPECIAL COLLECTION - EN | Colossal Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHARIZARD EX SPECIAL COLLECTION - EN | Colossal Store\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-05T17:43:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/charizard-ex-special-collection-ingles-pokemon-tcg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/\",\"name\":\"CHARIZARD EX SPECIAL COLLECTION - EN | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/charizard-ex-special-collection-ingles-pokemon-tcg.webp\",\"datePublished\":\"2025-07-25T12:10:30+00:00\",\"dateModified\":\"2025-08-05T17:43:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/charizard-ex-special-collection-ingles-pokemon-tcg.webp\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/charizard-ex-special-collection-ingles-pokemon-tcg.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CHARIZARD EX SPECIAL COLLECTION &#8211; EN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHARIZARD EX SPECIAL COLLECTION - EN | Colossal Store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/","og_locale":"en_US","og_type":"article","og_title":"CHARIZARD EX SPECIAL COLLECTION - EN | Colossal Store","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/","og_site_name":"Colossal Store","article_modified_time":"2025-08-05T17:43:53+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/charizard-ex-special-collection-ingles-pokemon-tcg.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/","url":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/","name":"CHARIZARD EX SPECIAL COLLECTION - EN | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/charizard-ex-special-collection-ingles-pokemon-tcg.webp","datePublished":"2025-07-25T12:10:30+00:00","dateModified":"2025-08-05T17:43:53+00:00","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/charizard-ex-special-collection-ingles-pokemon-tcg.webp","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/charizard-ex-special-collection-ingles-pokemon-tcg.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/tcg\/pokemon\/charizard-ex-special-collection-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"CHARIZARD EX SPECIAL COLLECTION &#8211; EN"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/11118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=11118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/11120"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=11118"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=11118"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=11118"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=11118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}