{"id":10724,"date":"2025-07-19T12:19:37","date_gmt":"2025-07-19T10:19:37","guid":{"rendered":"https:\/\/www.colossalstore.es\/?post_type=product&#038;p=10724"},"modified":"2025-07-19T12:19:38","modified_gmt":"2025-07-19T10:19:38","slug":"el-frutal","status":"publish","type":"product","link":"https:\/\/www.colossalstore.es\/en\/tienda\/juegos-de-mesa\/el-frutal\/","title":{"rendered":"EL FRUTAL"},"content":{"rendered":"<p>Los \u00e1rboles del Frutal est\u00e1n cargados de frutas y el p\u00edcaro cuervo quiere hacerse con todas. Los jugadores intentan cosechar la fruta antes que el cuervo. En funci\u00f3n del dado, los jugadores podr\u00e1n recolectar una o dos frutas de un \u00e1rbol e introducirlas en la cesta o colocar una pieza de puzzle en el centro del tablero. Si consiguen recolectar toda la fruta antes de que el puzzle del cuervo est\u00e9 terminado, los jugadores ganar\u00e1n la partida.<br \/>\nContent:<br \/>\n10 manzanas, 10 peras, 10 pares de cerezas, 10 ciruelas, 4 cestas para recolectar la fruta, 1 puzzle del cuervo (9 piezas), 1 dado de colores y s\u00edmbolos, 1 tablero.<br \/>\nIdioma de las instrucciones del juego:espa\u00f1ol<br \/>\nalem\u00e1n<br \/>\ningl\u00e9s<br \/>\nfranc\u00e9s<br \/>\nneerland\u00e9s<br \/>\nitaliano<br \/>\nAutores:Anneliese Farkaschovsky<br \/>\nIlustradores:Walter Matheis<br \/>\nTipo de deporte:juego cooperativo<br \/>\njuego de dados<br \/>\njuego de acumulaci\u00f3n<br \/>\nAdvertencias:Atenci\u00f3n. No apto para ni\u00f1os menores de 3 a\u00f1os. Piezas peque\u00f1as. Peligro de asfixia.<br \/>\nHasta X a\u00f1os de edad:6 a\u00f1os<br \/>\nDesde X a\u00f1os de edad:3 a\u00f1os<br \/>\nPeso del producto:1,071 kg<br \/>\nN\u00famero de jugadores hasta:8 personas<br \/>\nDuraci\u00f3n del juego desde:10 min<br \/>\nN\u00famero de jugadores desde:1 personas<br \/>\nDuraci\u00f3n del juego hasta:15 min<br \/>\nMaterial:cart\u00f3n, madera<\/p>","protected":false},"excerpt":{"rendered":"<p>Los \u00e1rboles del Frutal est\u00e1n cargados de frutas y el p\u00edcaro cuervo quiere hacerse con todas. Los jugadores intentan cosechar la fruta antes que el cuervo. En funci\u00f3n del dado, los jugadores podr\u00e1n recolectar una o dos frutas de un \u00e1rbol e introducirlas en la cesta o colocar una pieza de puzzle en el centro [&hellip;]<\/p>","protected":false},"featured_media":10727,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[26],"product_tag":[],"class_list":{"0":"post-10724","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-juegos-de-mesa","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EL FRUTAL | Colossal Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colossalstore.es\/en\/tienda\/juegos-de-mesa\/el-frutal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EL FRUTAL | Colossal Store\" \/>\n<meta property=\"og:description\" content=\"Los \u00e1rboles del Frutal est\u00e1n cargados de frutas y el p\u00edcaro cuervo quiere hacerse con todas. Los jugadores intentan cosechar la fruta antes que el cuervo. En funci\u00f3n del dado, los jugadores podr\u00e1n recolectar una o dos frutas de un \u00e1rbol e introducirlas en la cesta o colocar una pieza de puzzle en el centro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colossalstore.es\/en\/tienda\/juegos-de-mesa\/el-frutal\/\" \/>\n<meta property=\"og:site_name\" content=\"Colossal Store\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-19T10:19:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/g.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"528\" \/>\n\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Colossal_Store\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/\",\"url\":\"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/\",\"name\":\"EL FRUTAL | Colossal Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.colossalstore.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/g.jpg\",\"datePublished\":\"2025-07-19T10:19:37+00:00\",\"dateModified\":\"2025-07-19T10:19:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/#primaryimage\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/g.jpg\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/g.jpg\",\"width\":528,\"height\":528},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colossalstore.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.colossalstore.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EL FRUTAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colossalstore.es\/#website\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"name\":\"Colossal Store\",\"description\":\"Colossal Store, tienda especializada en TCGs.\",\"publisher\":{\"@id\":\"https:\/\/www.colossalstore.es\/#organization\"},\"alternateName\":\"Colossal Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colossalstore.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colossalstore.es\/#organization\",\"name\":\"Colossal Store\",\"url\":\"https:\/\/www.colossalstore.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"contentUrl\":\"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png\",\"width\":1181,\"height\":1181,\"caption\":\"Colossal Store\"},\"image\":{\"@id\":\"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Colossal_Store\",\"https:\/\/www.instagram.com\/colossal_store_tcg\/\",\"https:\/\/www.tiktok.com\/@colossalstore\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EL FRUTAL | Colossal Store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colossalstore.es\/en\/tienda\/juegos-de-mesa\/el-frutal\/","og_locale":"en_US","og_type":"article","og_title":"EL FRUTAL | Colossal Store","og_description":"Los \u00e1rboles del Frutal est\u00e1n cargados de frutas y el p\u00edcaro cuervo quiere hacerse con todas. Los jugadores intentan cosechar la fruta antes que el cuervo. En funci\u00f3n del dado, los jugadores podr\u00e1n recolectar una o dos frutas de un \u00e1rbol e introducirlas en la cesta o colocar una pieza de puzzle en el centro [&hellip;]","og_url":"https:\/\/www.colossalstore.es\/en\/tienda\/juegos-de-mesa\/el-frutal\/","og_site_name":"Colossal Store","article_modified_time":"2025-07-19T10:19:38+00:00","og_image":[{"width":528,"height":528,"url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/g.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Colossal_Store","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/","url":"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/","name":"EL FRUTAL | Colossal Store","isPartOf":{"@id":"https:\/\/www.colossalstore.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/#primaryimage"},"image":{"@id":"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/g.jpg","datePublished":"2025-07-19T10:19:37+00:00","dateModified":"2025-07-19T10:19:38+00:00","breadcrumb":{"@id":"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/#primaryimage","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/g.jpg","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2025\/07\/g.jpg","width":528,"height":528},{"@type":"BreadcrumbList","@id":"https:\/\/www.colossalstore.es\/tienda\/juegos-de-mesa\/el-frutal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colossalstore.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.colossalstore.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"EL FRUTAL"}]},{"@type":"WebSite","@id":"https:\/\/www.colossalstore.es\/#website","url":"https:\/\/www.colossalstore.es\/","name":"Colossal Store","description":"Colossal Store, store specialized in TCGs.","publisher":{"@id":"https:\/\/www.colossalstore.es\/#organization"},"alternateName":"Colossal Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colossalstore.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colossalstore.es\/#organization","name":"Colossal Store","url":"https:\/\/www.colossalstore.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","contentUrl":"https:\/\/www.colossalstore.es\/wp-content\/uploads\/2023\/05\/Colossal_Logo-02.png","width":1181,"height":1181,"caption":"Colossal Store"},"image":{"@id":"https:\/\/www.colossalstore.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Colossal_Store","https:\/\/www.instagram.com\/colossal_store_tcg\/","https:\/\/www.tiktok.com\/@colossalstore"]}]}},"_links":{"self":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product\/10724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/comments?post=10724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media\/10727"}],"wp:attachment":[{"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/media?parent=10724"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_brand?post=10724"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_cat?post=10724"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colossalstore.es\/en\/wp-json\/wp\/v2\/product_tag?post=10724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}